{"id":174665,"date":"2023-06-23T08:00:40","date_gmt":"2023-06-23T06:00:40","guid":{"rendered":"https:\/\/news.sap.com\/germany\/?p=174665"},"modified":"2023-06-19T13:55:33","modified_gmt":"2023-06-19T11:55:33","slug":"document-translation-sap-enable-now","status":"publish","type":"post","link":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/","title":{"rendered":"Document Translation: Unterst\u00fctzung globaler Softwareanwender in lokalen Sprachen"},"content":{"rendered":"<p class=\"lead\">Wenn man etwas Neues lernt, f\u00e4llt das Verstehen in der Muttersprache in der Regel leichter. Selbst, wenn man zwei, oder gar drei, vier oder f\u00fcnf Sprachen flie\u00dfend spricht. Deshalb wurde<a href=\"https:\/\/www.sap.com\/germany\/products\/hcm\/enable-now.html?url_id=text-de-newscenter:CRM-DX23-AAA-1904104_08\" target=\"_blank\" rel=\"noopener\" data-nuia-id=\"103\"> SAP\u00a0Enable Now<\/a> nun um den Service \u201eDocument Translation\u201c f\u00fcr <a href=\"https:\/\/www.sapstore.com\/solutions\/80248\/SAP-Translation-Hub\" target=\"_blank\" rel=\"noopener\" data-nuia-id=\"104\">SAP\u00a0Translation Hub<\/a> erweitert, mit dem Anwender Inhalte der In-App-Hilfe und E-Learning-Materialien mit einem Klick \u00fcbersetzen lassen k\u00f6nnen.<\/p>\n<p>Mit SAP Enable Now lassen sich eine In-App-Hilfe und E-Learning-Inhalte erstellen, bearbeiten und f\u00fcr Anwenderinnen und Anwender bereitstellen. Direkt in der Anwendung, die genutzt wird, l\u00e4sst sich auf die Hilfe zugreifen \u2013 unabh\u00e4ngig davon, ob es sich um eine L\u00f6sung von SAP oder eines Drittanbieters handelt. Die In-App-Hilfe unterst\u00fctzt bei allen Schritten in der Anwendung. Sie kann beispielsweise dabei helfen, bei der Dateneingabe Felder auszuf\u00fcllen oder sich einen \u00dcberblick \u00fcber die Aufgaben zu verschaffen, die sich mit der L\u00f6sung erledigen k\u00f6nnen. Dank der In-App-Hilfe lassen sich mehr Funktionen als bisher bekannt nutzen und so das Potenzial der L\u00f6sung optimal aussch\u00f6pfen.<\/p>\n<h2><strong>Was ist Document Translation?<\/strong><\/h2>\n<p>Mit dem Service \u201eDocument Translation\u201c f\u00fcr SAP Translation Hub k\u00f6nnen Texte und Dokumente durch den Einsatz von <a href=\"https:\/\/help.sap.com\/viewer\/9f73362817cd48339dd8a6acba160f7f\/\" target=\"_blank\" rel=\"noopener\" data-nuia-id=\"105\">maschineller \u00dcbersetzung<\/a> ohne Hilfestellung durch \u00dcbersetzungsteams oder R\u00fcckgriff auf \u00dcbersetzungs-Workflows direkt \u00fcbersetzen werden. Das Originaldokument muss \u00fcbermittelt werden, zur\u00fcck kommt dann das Dokument in der Sprache der Wahl. Das maschinelle \u00dcbersetzungssystem wurde so trainiert, dass es bei der \u00dcbersetzung von Dokumenten mit SAP-Inhalten bestm\u00f6gliche Ergebnisse erzielt. Der Service ist in den <a href=\"https:\/\/help.sap.com\/docs\/SAP_TRANSLATION_HUB\/9f73362817cd48339dd8a6acba160f7f\/6fc2e5ab04a94da4a0c3d0740a9bb2ff.html\" target=\"_blank\" rel=\"noopener\" data-nuia-id=\"106\">von SAP\u00a0Translation Hub unterst\u00fctzten Sprachen<\/a> verf\u00fcgbar. Document Translation ist ein eigenst\u00e4ndiger Service oder l\u00e4sst sich \u00fcber eine der vorhandenen Integrationen (z. B. in SAP Enable Now) nutzen.<\/p>\n<h2><strong>Die Vorteile von SAP\u00a0Enable Now und Document Translation kombinieren<\/strong><\/h2>\n<p>Die neuen Funktionen bieten vielf\u00e4ltige M\u00f6glichkeiten f\u00fcr Unternehmen, die auf globaler Ebene t\u00e4tig werden wollen. Kunden k\u00f6nnen damit Inhalte schneller verteilen \u2013 automatisch und mit geringem technischem Aufwand. Anwender k\u00f6nnen nun auch Tutorials und E-Learning-Inhalte automatisch \u00fcbersetzen lassen. Neben der Erstellung von In-App-Hilfe k\u00f6nnen au\u00dferdem die Standardinhalte von SAP Enable Now in vielen <a href=\"https:\/\/www.sap.com\/germany\/products.html?url_id=text-de-newscenter:CRM-DX23-AAA-1904104_08\" target=\"_blank\" rel=\"noopener\" data-nuia-id=\"107\">Cloudl\u00f6sungen von SAP<\/a> f\u00fcr Anwender angepasst werden.<\/p>\n<p>Und das Beste daran: Wer SAP Enable Now, Cloud Edition bereits abonniert hat, hat diesen Service bereits in der Subskription enthalten und kann ihn umgehend nutzen.<\/p>\n<p>\u201eSAP\u00a0Enable Now bietet Kunden die M\u00f6glichkeit, Inhalte in ihrer Sprache zu erstellen und ganz einfach f\u00fcr internationale Zielgruppen \u00fcbersetzen zu lassen\u201c, erkl\u00e4rt Sindhu Gangadharan, Senior Vice President und Gesch\u00e4ftsf\u00fchrerin der SAP\u00a0Labs Indien. \u201eEs freut uns sehr, dass wir Kunden diesen Service anbieten und ihnen damit eine schnelle und einfache Erschlie\u00dfung neuer M\u00e4rkte erm\u00f6glichen k\u00f6nnen.\u201c SAP\u00a0Enable Now und Document Translation sind Teil des Bereichs SAP\u00a0User Enablement, der ebenfalls von Sindhu Gangadharan geleitet wird.<\/p>\n<p>Durch die Integration der automatischen \u00dcbersetzungsfunktionen von SAP l\u00e4sst sich auch das Risiko mindern, dass global bereitgestellte Inhalte zur Unterst\u00fctzung von Kunden fehlerhaft oder unvollst\u00e4ndig sind. Kunden k\u00f6nnen sich nun darauf verlassen, dass ihre Inhalte korrekt in eine Vielzahl von Sprachen \u00fcbersetzt werden.<\/p>\n<p>Neu- und Bestandskunden von SAP Enable Now, Cloud Edition haben ab sofort Zugriff auf die maschinellen \u00dcbersetzungsfunktionen. Die Einf\u00fchrung dieser Funktionen ist ein wichtiger Schritt, der SAP-Kunden eine globale Ausweitung ihrer Gesch\u00e4ftst\u00e4tigkeit erm\u00f6glicht. Mit diesen Innovationen k\u00f6nnen sie darauf vertrauen, dass ihre Schulungsinhalte unkompliziert und unabh\u00e4ngig f\u00fcr globale Zielgruppen \u00fcbersetzt werden. So k\u00f6nnen Teams unterst\u00fctzt werden, ihr Wissen ohne Hilfestellung durch Projekt- und Autorenteams in der Sprache ihrer Wahl zu vertiefen.<\/p>\n<hr \/>\n<p><em><small>Kristina Kunad ist Global Solution Owner f\u00fcr SAP Enable Now.<\/small><\/em><br \/>\n<em><small>Ana Medina ist Product Manager f\u00fcr SAP Translation Hub.<\/small><\/em><br \/>\n<em><small>Fiona Murphy ist Product Manager f\u00fcr SAP Translation Hub.<\/small><\/em><br \/>\n<em><small>Kerstin Bier ist Solution Owner f\u00fcr SAP Translation Hub.<\/small><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn man etwas Neues lernt, f\u00e4llt das Verstehen in der Muttersprache in der Regel leichter. Selbst, wenn man zwei, oder gar drei, vier oder f\u00fcnf&#8230;<\/p>\n","protected":false},"author":4516,"featured_media":174667,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"related_posts":[],"footnotes":"","_links_to":"","_links_to_target":""},"categories":[45272,5569858],"tags":[5624194,5630255,5622695],"series":[],"sapn-display":[5630499,5630502,3848,45027],"sapn-type":[45277],"class_list":["post-174665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-losungen","category-services-support","tag-e-learning","tag-employee-experience","tag-intelligentes-unternehmen","sapn-display-feature-hero","sapn-display-feature-spotlight","sapn-display-top-stories","sapn-display-hero","sapn-type-feature"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Document Translation in SAP Enable Now | SAP News Center<\/title>\n<meta name=\"description\" content=\"SAP Enable Now, cloud edition beinhaltet jetzt Document Translation f\u00fcr SAP Translation Hub. Erfahren Sie mehr \u00fcber die Integration!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Document Translation: Unterst\u00fctzung globaler Softwareanwender in lokalen Sprachen\" \/>\n<meta property=\"og:description\" content=\"SAP Enable Now, cloud edition beinhaltet jetzt Document Translation f\u00fcr SAP Translation Hub. Erfahren Sie mehr \u00fcber die Integration!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/\" \/>\n<meta property=\"og:site_name\" content=\"SAP News Center\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-23T06:00:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/news.sap.com\/germany\/files\/2023\/06\/16\/278026_278026_h_ergb_s_gl_FEATURE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SAPdach\" \/>\n<meta name=\"twitter:site\" content=\"@SAPdach\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/2023\\\/06\\\/document-translation-sap-enable-now\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/2023\\\/06\\\/document-translation-sap-enable-now\\\/\"},\"author\":{\"name\":\"Ana Medina\",\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/#\\\/schema\\\/person\\\/26907402a70e221395bd3c669c2b8838\"},\"headline\":\"Document Translation: Unterst\u00fctzung globaler Softwareanwender in lokalen Sprachen\",\"datePublished\":\"2023-06-23T06:00:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/2023\\\/06\\\/document-translation-sap-enable-now\\\/\"},\"wordCount\":648,\"image\":{\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/2023\\\/06\\\/document-translation-sap-enable-now\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/files\\\/2023\\\/06\\\/16\\\/278026_278026_h_ergb_s_gl_FEATURE.jpg\",\"keywords\":[\"E-Learning\",\"Employee Experience\",\"Intelligentes Unternehmen\"],\"articleSection\":[\"L\u00f6sungen\",\"Services und Support\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/2023\\\/06\\\/document-translation-sap-enable-now\\\/\",\"url\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/2023\\\/06\\\/document-translation-sap-enable-now\\\/\",\"name\":\"Document Translation in SAP Enable Now | SAP News Center\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/2023\\\/06\\\/document-translation-sap-enable-now\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/2023\\\/06\\\/document-translation-sap-enable-now\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/files\\\/2023\\\/06\\\/16\\\/278026_278026_h_ergb_s_gl_FEATURE.jpg\",\"datePublished\":\"2023-06-23T06:00:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/#\\\/schema\\\/person\\\/26907402a70e221395bd3c669c2b8838\"},\"description\":\"SAP Enable Now, cloud edition beinhaltet jetzt Document Translation f\u00fcr SAP Translation Hub. Erfahren Sie mehr \u00fcber die Integration!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/2023\\\/06\\\/document-translation-sap-enable-now\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/news.sap.com\\\/germany\\\/2023\\\/06\\\/document-translation-sap-enable-now\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/2023\\\/06\\\/document-translation-sap-enable-now\\\/#primaryimage\",\"url\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/files\\\/2023\\\/06\\\/16\\\/278026_278026_h_ergb_s_gl_FEATURE.jpg\",\"contentUrl\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/files\\\/2023\\\/06\\\/16\\\/278026_278026_h_ergb_s_gl_FEATURE.jpg\",\"width\":1920,\"height\":600,\"caption\":\"Document Translation f\u00fcr SAP Translation Hub\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/2023\\\/06\\\/document-translation-sap-enable-now\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Document Translation: Unterst\u00fctzung globaler Softwareanwender in lokalen Sprachen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/#website\",\"url\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/\",\"name\":\"SAP News Center\",\"description\":\"Unternehmensberichte &amp; Presseportal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/#\\\/schema\\\/person\\\/26907402a70e221395bd3c669c2b8838\",\"name\":\"Ana Medina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=blank&r=g\",\"caption\":\"Ana Medina\"},\"url\":\"https:\\\/\\\/news.sap.com\\\/germany\\\/author\\\/anamedina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Document Translation in SAP Enable Now | SAP News Center","description":"SAP Enable Now, cloud edition beinhaltet jetzt Document Translation f\u00fcr SAP Translation Hub. Erfahren Sie mehr \u00fcber die Integration!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/","og_locale":"de_DE","og_type":"article","og_title":"Document Translation: Unterst\u00fctzung globaler Softwareanwender in lokalen Sprachen","og_description":"SAP Enable Now, cloud edition beinhaltet jetzt Document Translation f\u00fcr SAP Translation Hub. Erfahren Sie mehr \u00fcber die Integration!","og_url":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/","og_site_name":"SAP News Center","article_published_time":"2023-06-23T06:00:40+00:00","og_image":[{"width":1920,"height":600,"url":"https:\/\/news.sap.com\/germany\/files\/2023\/06\/16\/278026_278026_h_ergb_s_gl_FEATURE.jpg","type":"image\/jpeg"}],"author":"Ana Medina","twitter_card":"summary_large_image","twitter_creator":"@SAPdach","twitter_site":"@SAPdach","twitter_misc":{"Verfasst von":"Ana Medina","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/#article","isPartOf":{"@id":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/"},"author":{"name":"Ana Medina","@id":"https:\/\/news.sap.com\/germany\/#\/schema\/person\/26907402a70e221395bd3c669c2b8838"},"headline":"Document Translation: Unterst\u00fctzung globaler Softwareanwender in lokalen Sprachen","datePublished":"2023-06-23T06:00:40+00:00","mainEntityOfPage":{"@id":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/"},"wordCount":648,"image":{"@id":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/#primaryimage"},"thumbnailUrl":"https:\/\/news.sap.com\/germany\/files\/2023\/06\/16\/278026_278026_h_ergb_s_gl_FEATURE.jpg","keywords":["E-Learning","Employee Experience","Intelligentes Unternehmen"],"articleSection":["L\u00f6sungen","Services und Support"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/","url":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/","name":"Document Translation in SAP Enable Now | SAP News Center","isPartOf":{"@id":"https:\/\/news.sap.com\/germany\/#website"},"primaryImageOfPage":{"@id":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/#primaryimage"},"image":{"@id":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/#primaryimage"},"thumbnailUrl":"https:\/\/news.sap.com\/germany\/files\/2023\/06\/16\/278026_278026_h_ergb_s_gl_FEATURE.jpg","datePublished":"2023-06-23T06:00:40+00:00","author":{"@id":"https:\/\/news.sap.com\/germany\/#\/schema\/person\/26907402a70e221395bd3c669c2b8838"},"description":"SAP Enable Now, cloud edition beinhaltet jetzt Document Translation f\u00fcr SAP Translation Hub. Erfahren Sie mehr \u00fcber die Integration!","breadcrumb":{"@id":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/#primaryimage","url":"https:\/\/news.sap.com\/germany\/files\/2023\/06\/16\/278026_278026_h_ergb_s_gl_FEATURE.jpg","contentUrl":"https:\/\/news.sap.com\/germany\/files\/2023\/06\/16\/278026_278026_h_ergb_s_gl_FEATURE.jpg","width":1920,"height":600,"caption":"Document Translation f\u00fcr SAP Translation Hub"},{"@type":"BreadcrumbList","@id":"https:\/\/news.sap.com\/germany\/2023\/06\/document-translation-sap-enable-now\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/news.sap.com\/germany\/"},{"@type":"ListItem","position":2,"name":"Document Translation: Unterst\u00fctzung globaler Softwareanwender in lokalen Sprachen"}]},{"@type":"WebSite","@id":"https:\/\/news.sap.com\/germany\/#website","url":"https:\/\/news.sap.com\/germany\/","name":"SAP News Center","description":"Unternehmensberichte &amp; Presseportal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/news.sap.com\/germany\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/news.sap.com\/germany\/#\/schema\/person\/26907402a70e221395bd3c669c2b8838","name":"Ana Medina","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=blank&r=g","caption":"Ana Medina"},"url":"https:\/\/news.sap.com\/germany\/author\/anamedina\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/news.sap.com\/germany\/wp-json\/wp\/v2\/posts\/174665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/news.sap.com\/germany\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/news.sap.com\/germany\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/news.sap.com\/germany\/wp-json\/wp\/v2\/users\/4516"}],"replies":[{"embeddable":true,"href":"https:\/\/news.sap.com\/germany\/wp-json\/wp\/v2\/comments?post=174665"}],"version-history":[{"count":0,"href":"https:\/\/news.sap.com\/germany\/wp-json\/wp\/v2\/posts\/174665\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/news.sap.com\/germany\/wp-json\/wp\/v2\/media\/174667"}],"wp:attachment":[{"href":"https:\/\/news.sap.com\/germany\/wp-json\/wp\/v2\/media?parent=174665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/news.sap.com\/germany\/wp-json\/wp\/v2\/categories?post=174665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/news.sap.com\/germany\/wp-json\/wp\/v2\/tags?post=174665"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/news.sap.com\/germany\/wp-json\/wp\/v2\/series?post=174665"},{"taxonomy":"sapn-display","embeddable":true,"href":"https:\/\/news.sap.com\/germany\/wp-json\/wp\/v2\/sapn-display?post=174665"},{"taxonomy":"sapn-type","embeddable":true,"href":"https:\/\/news.sap.com\/germany\/wp-json\/wp\/v2\/sapn-type?post=174665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}